{"id":85,"date":"2010-05-03T18:06:46","date_gmt":"2010-05-03T18:06:46","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/23artistas\/?p=85"},"modified":"2024-06-02T21:08:19","modified_gmt":"2024-06-02T21:08:19","slug":"vamos-devorar-livros","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/23artistas\/2010\/05\/03\/vamos-devorar-livros\/","title":{"rendered":"Vamos devorar livros?"},"content":{"rendered":"<p><a href=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/reconto-Jo\u00e3o.jpg\"><\/a><\/p>\n<p>Na semana\u00a0dedicada \u00e0 leitura, a nossa professora estagi\u00e1ria, presenteou-nos com uma hist\u00f3ria que falava de um menino que gostava de comer livros, pensando ele que ao faz\u00ea-lo iria ficar mais esperto, contudo, as coisas n\u00e3o correram l\u00e1 muito bem, e depois de aconselhado, desistiu de os comer com a boca, passando a com\u00ea-los com os olhos. No final da hist\u00f3ria, o menino, que se chamava Henrique, descobre os prazeres da leitura e que atrav\u00e9s da leitura, poderia vir a tornar-se realmente o menino mais esperto do mundo.<\/p>\n<p><a href=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/IMG_0421.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"86\" data-permalink=\"https:\/\/blogs.ess-edu.pt\/23artistas\/2010\/05\/03\/vamos-devorar-livros\/img_0421\/\" data-orig-file=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/IMG_0421.jpg\" data-orig-size=\"659,494\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon DIGITAL IXUS 40&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1272283212&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.8&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"IMG_0421\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/IMG_0421.jpg\" class=\"alignnone size-thumbnail wp-image-86\" title=\"IMG_0421\" src=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/IMG_0421-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><a href=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/Reconto-Diogo-R.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"134\" data-permalink=\"https:\/\/blogs.ess-edu.pt\/23artistas\/2010\/05\/03\/vamos-devorar-livros\/reconto-diogo-r\/\" data-orig-file=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/Reconto-Diogo-R..jpg\" data-orig-size=\"508,700\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Reconto Diogo R.\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/Reconto-Diogo-R..jpg\" class=\"alignnone size-thumbnail wp-image-134\" title=\"Reconto Diogo R.\" src=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/Reconto-Diogo-R.-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0<a href=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/reconto-Jo\u00e3o1.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"137\" data-permalink=\"https:\/\/blogs.ess-edu.pt\/23artistas\/2010\/05\/03\/vamos-devorar-livros\/reconto-joao-2\/\" data-orig-file=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/reconto-Jo\u00e3o1.jpg\" data-orig-size=\"391,539\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"reconto Jo\u00e3o\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/reconto-Jo\u00e3o1.jpg\" class=\"alignnone size-thumbnail wp-image-137\" title=\"reconto Jo\u00e3o\" src=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/reconto-Jo\u00e3o1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>Depois de descobrir-mos n\u00f3s tamb\u00e9m as vantagens da leitura, escrevemos algumas frases sobre o livro que coloc\u00e1mos no nosso cantinho da leitura e da escrita.<\/p>\n<p><a href=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/IMG_0431.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"87\" data-permalink=\"https:\/\/blogs.ess-edu.pt\/23artistas\/2010\/05\/03\/vamos-devorar-livros\/img_0431\/\" data-orig-file=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/IMG_0431.jpg\" data-orig-size=\"682,511\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon DIGITAL IXUS 40&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1272366719&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.8&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"IMG_0431\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/IMG_0431.jpg\" class=\"alignnone size-thumbnail wp-image-87\" title=\"IMG_0431\" src=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/IMG_0431-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0<a href=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/03052010465.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"138\" data-permalink=\"https:\/\/blogs.ess-edu.pt\/23artistas\/2010\/05\/03\/vamos-devorar-livros\/attachment\/03052010465\/\" data-orig-file=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/03052010465.jpg\" data-orig-size=\"922,691\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;5800 Xpres&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1272888985&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.7&quot;,&quot;iso&quot;:&quot;79&quot;,&quot;shutter_speed&quot;:&quot;0.03&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"03052010465\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/03052010465.jpg\" class=\"alignnone size-thumbnail wp-image-138\" title=\"03052010465\" src=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/03052010465-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>\u00a0<a href=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/03052010466.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"139\" data-permalink=\"https:\/\/blogs.ess-edu.pt\/23artistas\/2010\/05\/03\/vamos-devorar-livros\/attachment\/03052010466\/\" data-orig-file=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/03052010466.jpg\" data-orig-size=\"922,691\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;5800 Xpres&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1272889031&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.7&quot;,&quot;iso&quot;:&quot;112&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"03052010466\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/03052010466.jpg\" class=\"alignnone size-thumbnail wp-image-139\" title=\"03052010466\" src=\"https:\/\/blogs.ess-edu.pt\/23artistas\/files\/2010\/05\/03052010466-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>Pois \u00e9, o livro \u00e9 muito importante para todos n\u00f3s, com ele podemos aprender muitas coisas.<\/p>\n<p>Afinal, o livro \u00e9 um p\u00e1ssaro com mais de cem asas para voar. N\u00e3o concordam?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na semana\u00a0dedicada \u00e0 leitura, a nossa professora estagi\u00e1ria, presenteou-nos com uma hist\u00f3ria que falava de um menino que gostava de comer livros, pensando ele que ao faz\u00ea-lo iria ficar mais esperto, contudo, as coisas n\u00e3o correram l\u00e1 muito bem, e depois de aconselhado, desistiu de os comer com a boca, passando a com\u00ea-los com os [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-85","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunZ2-1n","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/23artistas\/wp-json\/wp\/v2\/posts\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/23artistas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/23artistas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/23artistas\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/23artistas\/wp-json\/wp\/v2\/comments?post=85"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/23artistas\/wp-json\/wp\/v2\/posts\/85\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/23artistas\/wp-json\/wp\/v2\/media?parent=85"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/23artistas\/wp-json\/wp\/v2\/categories?post=85"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/23artistas\/wp-json\/wp\/v2\/tags?post=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}