{"id":330,"date":"2009-03-24T15:19:26","date_gmt":"2009-03-24T15:19:26","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/ap12a2008\/?p=330"},"modified":"2024-07-15T23:32:47","modified_gmt":"2024-07-15T23:32:47","slug":"euro-deputado-miguel-portas-na-escola","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/03\/24\/euro-deputado-miguel-portas-na-escola\/","title":{"rendered":"Euro Deputado Miguel Portas na Escola"},"content":{"rendered":"<p>Na passada sexta-feira, 20 de Mar\u00e7o, esteve presente no Audit\u00f3rio da nossa escola, para um debate sobre a Europa e a crise financeira, o euro deputado Miguel Portas. O debate teve in\u00edcio \u00e0s 21:30 horas e terminou por volta da meia-noite. Houve muita ades\u00e3o a este debate. Estiveram presentes alunos, professores e um representante da imprensa local.<\/p>\n<p>Foram debatidos temas como a crise na Europa e em Portugal em particular, com a apresenta\u00e7\u00e3o de gr\u00e1ficos referentes \u00e1 economia nacional e ao desemprego.<\/p>\n<p>Aprovamos estas e outras iniciativas promovidas pela nossa Associa\u00e7\u00e3o de Estudantes.<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Na passada sexta-feira, 20 de Mar\u00e7o, esteve presente no Audit\u00f3rio da nossa escola, para um debate sobre a Europa e a crise financeira, o euro deputado Miguel Portas. O debate teve in\u00edcio \u00e0s 21:30 horas e terminou por volta da meia-noite. Houve muita ades\u00e3o a este debate. Estiveram presentes alunos, professores e um representante da [&#8230;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[76],"tags":[],"class_list":["post-330","post","type-post","status-publish","format-standard","hentry","category-eventos","odd"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunJ5-5k","jetpack-related-posts":[{"id":186,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/01\/06\/programa-comenius\/","url_meta":{"origin":330,"position":0},"title":"Programa Comenius","author":"Helena Sebastiana","date":"6 06+00:00 Janeiro 06+00:00 2009","format":false,"excerpt":"Segundo a Professora Maria Jos\u00e9 Alvelos, o programa Comenius pretende desenvolver a dimens\u00e3o europeia nas escolas participantes, tendo em vista o refor\u00e7o da cidadania europeia para o conhecimento e preserva\u00e7\u00e3o da heran\u00e7a cultural, hist\u00f3rica e social dos pa\u00edses envolvidos. Tem como finalidade o enriquecimento das aprendizagens s\u00f3cio-culturais dos alunos e\u2026","rel":"","context":"In &quot;Clubes&quot;","block_context":{"text":"Clubes","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/clubes\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":438,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/05\/05\/viagem-de-estudo-do-5%c2%baano\/","url_meta":{"origin":330,"position":1},"title":"Viagem de estudo do 5.\u00ba ano","author":"Helena Sebastiana","date":"5 05+00:00 Maio 05+00:00 2009","format":false,"excerpt":"No dia 17 de Abril de 2009, as turmas do 5.\u00ba ano da nossa escola, realizaram uma visita de estudo a Guimar\u00e3es e Braga. Na parte da manh\u00e3, os alunos dividiram-se em dois grupos. O primeiro grupo visitou o Pa\u00e7o dos Duques de Bragan\u00e7a. E o segundo visitou o Castelo\u2026","rel":"","context":"In &quot;Viagens de estudo&quot;","block_context":{"text":"Viagens de estudo","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/viagens-de-estudo\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":316,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/03\/24\/feira-das-profissoes-em-armamar\/","url_meta":{"origin":330,"position":2},"title":"Feira das Profiss\u00f5es em Armamar","author":"Helena Sebastiana","date":"24 24+00:00 Mar\u00e7o 24+00:00 2009","format":false,"excerpt":"Hoje, dia 24 de Mar\u00e7o de 2009, a Cristina, o Mik\u00e1, a Carolina, a C\u00e1tia e a Marina do 12.\u00ba A, o Diogo e a Joana do 10.\u00ba B e um grupo de professores foram divulgar a nossa escola a Armamar, numa feira de profiss\u00f5es promovida pela Escola B\u00e1sica\/2,3 Gomes\u2026","rel":"","context":"In &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/eventos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":530,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/05\/28\/a-minha-passagem-pela-escola-20032009-3\/","url_meta":{"origin":330,"position":3},"title":"A minha passagem pela escola &#8211; 2003\/2009","author":"Helena Sebastiana","date":"28 28+00:00 Maio 28+00:00 2009","format":false,"excerpt":"Foi h\u00e1 6 anos atr\u00e1s, em 2003, que deixei a EB 2,3 de Lamego, tamb\u00e9m conhecida como \u201cciclo\u201d, e vim estudar para esta escola. No in\u00edcio, foi um pouco dif\u00edcil por causa dos meus amigos do ciclo que foram, quase todos, para o Liceu. S\u00f3 viemos tr\u00eas para a S\u00e9.\u2026","rel":"","context":"In &quot;A minha passagem pela escola&quot;","block_context":{"text":"A minha passagem pela escola","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/a-minha-passagem-pela-escola\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":510,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/05\/21\/o-jantar-em-homenagem-aos-professores-e-funcionarios-reformados\/","url_meta":{"origin":330,"position":4},"title":"O jantar em homenagem aos professores e funcion\u00e1rios reformados","author":"Helena Sebastiana","date":"21 21+00:00 Maio 21+00:00 2009","format":false,"excerpt":"Na passada ter\u00e7a-feira, dia 19, realizou-se um jantar na escola dedicado aos professores e funcion\u00e1rios que se reformaram desde 2005. O jantar de conv\u00edvio foi seguido por uma pe\u00e7a de teatro encenada pelos professores, \u201cO percurso dos professores\u201d, e foi visualizado tamb\u00e9m o filme \u201cA nossa escola\u201d, realizado pela nossa\u2026","rel":"","context":"In &quot;Aconteceu...&quot;","block_context":{"text":"Aconteceu...","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/aconteceu\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":491,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/05\/14\/ii-montra-de-oportunidades\/","url_meta":{"origin":330,"position":5},"title":"II Montra de Oportunidades","author":"Helena Sebastiana","date":"14 14+00:00 Maio 14+00:00 2009","format":false,"excerpt":"Na passada quarta-feira, dia 13 de Maio, iniciou-se a II Montra de Oportunidades, no Largo da Feira em Lamego, com o objectivo de divulgar diferentes cursos, escolas b\u00e1sicas, secund\u00e1rias, profissionais e universidades do pa\u00eds. Tamb\u00e9m a nossa escola esteve presente nesta iniciativa. Al\u00e9m de um espa\u00e7o destinado \u00e0 exposi\u00e7\u00e3o de\u2026","rel":"","context":"In &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/eventos\/"},"img":{"alt_text":"imagem0771","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/05\/imagem0771-150x120.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/posts\/330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/comments?post=330"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/posts\/330\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/media?parent=330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/categories?post=330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/tags?post=330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}