{"id":400,"date":"2009-04-30T16:08:04","date_gmt":"2009-04-30T16:08:04","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/ap12a2008\/?p=400"},"modified":"2024-07-16T10:36:13","modified_gmt":"2024-07-16T10:36:13","slug":"a-minha-viagem-de-finalistas-by-daniela","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/04\/30\/a-minha-viagem-de-finalistas-by-daniela\/","title":{"rendered":"A minha viagem de Finalistas &#8211; By Daniela"},"content":{"rendered":"<p>Foi no dia 27 de Mar\u00e7o que se iniciou uma viagem muito esperada por mim! Tinha chegado o dia da viagem de finalistas!<\/p>\n<p>Quando cheguei a Lloret de Mar era tudo espectacular. Fiquei sem palavras! Lloret estava cheia de pessoas, muita anima\u00e7\u00e3o, muita m\u00fasica e muita cor. Nem a chuva, nem as m\u00e1s condi\u00e7\u00f5es do quarto conseguiram \u201cdeitar abaixo\u201d toda a emo\u00e7\u00e3o que eu estava a sentir.<\/p>\n<p>Foram dias \u00fanicos que nunca mais se voltar\u00e3o a repetir!<\/p>\n<p>Fiz uma visita tur\u00edstica a Lloret, subi a uma ravina para apreciar a vista, visitei uma casa particular com aspecto de castelo, passeei \u00e0 beira-mar, fui \u00e0 praia e participei na divers\u00e3o da noite. Para al\u00e9m de ter conhecido pessoas novas, tamb\u00e9m estive com amigos de Lamego. Cada vez que encontr\u00e1vamos pessoas de Lamego, faz\u00edamos uma festa e grit\u00e1vamos bem alto \u201cViva Lamego!\u201d.<\/p>\n<p>No dia 1 de Abril, j\u00e1 com o final da viagem no horizonte, fui ao parque de divers\u00f5es PortAventura. Nunca tinha ido a um parque de divers\u00f5es e posso dizer que a experi\u00eancia \u00e9 emocionante e \u00fanica. Adorei andar naquelas montanhas russas e consegui, por alguns momentos, deixar o meu medo das alturas. Posso dizer que \u00e9 uma experi\u00eancia que quero repetir.<\/p>\n<p>Na viagem de regresso,\u00a0 pass\u00e1mos em Barcelona e apesar de n\u00e3o ter visitado a cidade, achei-a m\u00e1gica. Quando vinha no autocarro s\u00f3 pensava na viagem e em todos os momentos bons que l\u00e1 tinha passado. Foi com muita pena, mas cheia de felicidade que deixei Lloret para tr\u00e1s e voltei para Lamego.<\/p>\n<p>At\u00e9 sempre, Lloret!<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 0pt; text-align: justify;\"><a href=\"https:\/\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/04\/img_3817.jpg\"><span style=\"font-size: 12pt;\"><span style=\"font-family: Calibri;\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"401\" data-permalink=\"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/04\/30\/a-minha-viagem-de-finalistas-by-daniela\/img_3817\/\" data-orig-file=\"https:\/\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/04\/img_3817.jpg\" data-orig-size=\"235,314\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon DIGITAL IXUS 80 IS&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1238358908&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;6.2&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"img_3817\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/04\/img_3817.jpg\" class=\"aligncenter size-medium wp-image-401\" src=\"https:\/\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/04\/img_3817-224x300.jpg\" alt=\"img_3817\" width=\"224\" height=\"300\" srcset=\"https:\/\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/04\/img_3817-224x300.jpg 224w, https:\/\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/04\/img_3817.jpg 235w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/span><\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi no dia 27 de Mar\u00e7o que se iniciou uma viagem muito esperada por mim! Tinha chegado o dia da viagem de finalistas!<\/p>\n<p>Quando cheguei a Lloret de Mar era tudo espectacular. Fiquei sem palavras! Lloret estava cheia de pessoas, muita anima\u00e7\u00e3o, muita m\u00fasica e muita cor. Nem a chuva, nem as m\u00e1s condi\u00e7\u00f5es do [&#8230;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[73],"tags":[],"class_list":["post-400","post","type-post","status-publish","format-standard","hentry","category-finalistas","odd"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunJ5-6s","jetpack-related-posts":[{"id":319,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/03\/24\/viagem-de-finalistas\/","url_meta":{"origin":400,"position":0},"title":"Viagem de Finalistas","author":"Helena Sebastiana","date":"24 24+00:00 Mar\u00e7o 24+00:00 2009","format":false,"excerpt":"Na pr\u00f3xima, Sexta-Feira, dia 27, os finalistas da nossa escola ir\u00e3o ter a sua t\u00e3o esperada, viagem de finalistas\u2026 A viagem ser\u00e1 de 8 dias e ter\u00e1 como destino Lloret de Mar. A partida de Lamego ser\u00e1 \u00e0s 21 horas de sexta-feira. Os alunos est\u00e3o t\u00e3o animados que come\u00e7aram a\u2026","rel":"","context":"In &quot;Finalistas&quot;","block_context":{"text":"Finalistas","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/finalistas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/03\/lollloret-299x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":386,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/04\/30\/a-minha-viagem-de-finalistas-by-sandra\/","url_meta":{"origin":400,"position":1},"title":"A minha viagem de Finalistas &#8211; By Sandra","author":"Helena Sebastiana","date":"30 30+00:00 Abril 30+00:00 2009","format":false,"excerpt":"Sem d\u00favida, \u00e9 dif\u00edcil traduzir em palavras o qu\u00e3o grandiosa foi esta viagem. Tudo come\u00e7ou quando o autocarro com destino a Lloret chegou a Lamego, nem quer\u00edamos acreditar que a viagem que prepar\u00e1mos durante meses e com que sonh\u00e1mos, ao longo de anos, estivesse t\u00e3o pr\u00f3xima de se realizar. Foi\u2026","rel":"","context":"In &quot;Finalistas&quot;","block_context":{"text":"Finalistas","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/finalistas\/"},"img":{"alt_text":"clip_image0026","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/04\/clip_image0026-300x224.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":353,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/04\/23\/a-minha-viagem-de-finalistas-a-lloret-de-mar-by-ricardo-2\/","url_meta":{"origin":400,"position":2},"title":"A minha viagem de Finalistas a LLoret de Mar&#8230; By Ricardo","author":"Helena Sebastiana","date":"23 23+00:00 Abril 23+00:00 2009","format":false,"excerpt":"Esta viagem foi espectacular. Foi uma das melhores viagens que j\u00e1 fiz. Fui com os meus amigos e diverti-me imenso, conheci novas pessoas e fiz novas amizades. O que eu menos gostei foi do tempo. N\u00e3o estava l\u00e1 muito bom. Mas mesmo assim, a viagem correu muito bem. O tempo\u2026","rel":"","context":"In &quot;Finalistas&quot;","block_context":{"text":"Finalistas","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/finalistas\/"},"img":{"alt_text":"clip_image0022","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/04\/clip_image0022-300x224.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":378,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/04\/30\/a-minha-experiencia-pessoal-a-lloret-de-mar-by-anabela\/","url_meta":{"origin":400,"position":3},"title":"A minha experi\u00eancia pessoal a LLoret de Mar &#8211; By Anabela","author":"Helena Sebastiana","date":"30 30+00:00 Abril 30+00:00 2009","format":false,"excerpt":"Bem, para come\u00e7ar, acho que n\u00e3o tenho palavras para descrever o qu\u00e3o gratificante e enriquecedora foi a viagem\u2026 Em primeiro lugar, foi a primeira vez que maior parte das pessoas fizeram uma Viagem assim. Por outro lado, esta viagem foi t\u00e3o esperada. Foram doze anos de espera! Finalmente, seria a\u00ed\u2026","rel":"","context":"In &quot;Finalistas&quot;","block_context":{"text":"Finalistas","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/finalistas\/"},"img":{"alt_text":"clip_image0023","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/04\/clip_image0023-300x224.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":418,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/05\/05\/a-minha-viagem-de-finalistas-by-marina\/","url_meta":{"origin":400,"position":4},"title":"A minha viagem de Finalistas &#8211; By Marina","author":"Helena Sebastiana","date":"5 05+00:00 Maio 05+00:00 2009","format":false,"excerpt":"Dia 27 de Mar\u00e7o, o dia mais esperado, o dia mais desejado da minha vida de estudante. Foi o dia em \u00a0que parti rumo a Lloret de Mar. Estava ansiosa para descobrir o que estava par l\u00e1 da fronteira, para l\u00e1 de Portugal! Foi uma viagem longa e cansativa, mas\u2026","rel":"","context":"In &quot;Finalistas&quot;","block_context":{"text":"Finalistas","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/finalistas\/"},"img":{"alt_text":"dsc00170","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/05\/dsc00170-300x224.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":379,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/04\/30\/a-minha-viagem-de-finalistas-by-tiago\/","url_meta":{"origin":400,"position":5},"title":"A minha viagem de Finalistas &#8211; By Tiago","author":"Helena Sebastiana","date":"30 30+00:00 Abril 30+00:00 2009","format":false,"excerpt":"Talvez indescrit\u00edvel seja a palavra mais adequada para descrever a viagem a Lloret. Fui com o objectivo de me divertir e \u201csocializar\u201d\u2026 e foi o que aconteceu. Conheci muita gente, o que tornou a viagem marcante pelo lado positivo. Todos os que foram no nosso autocarro, o pessoal da Em\u00eddio\u2026","rel":"","context":"In &quot;Finalistas&quot;","block_context":{"text":"Finalistas","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/finalistas\/"},"img":{"alt_text":"img_3834","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/04\/img_3834-300x225.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/posts\/400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/comments?post=400"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/posts\/400\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/media?parent=400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/categories?post=400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/tags?post=400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}