{"id":509,"date":"2009-05-21T15:37:20","date_gmt":"2009-05-21T15:37:20","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/ap12a2008\/?p=509"},"modified":"2024-07-16T15:25:50","modified_gmt":"2024-07-16T15:25:50","slug":"feira-do-livro","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/05\/21\/feira-do-livro\/","title":{"rendered":"Feira do Livro"},"content":{"rendered":"<p>Convidam-se todos os interessados e apreciadores de um bom livro a visitar a Feira do Livro que estar\u00e1 aberta ao p\u00fablico at\u00e9 ao dia 24 de Maio.<\/p>\n<p>\u201cPerde-te no mundo dos livros!\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Convidam-se todos os interessados e apreciadores de um bom livro a visitar a Feira do Livro que estar\u00e1 aberta ao p\u00fablico at\u00e9 ao dia 24 de Maio.<\/p>\n<p>\u201cPerde-te no mundo dos livros!\u201d<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[76],"tags":[],"class_list":["post-509","post","type-post","status-publish","format-standard","hentry","category-eventos","odd"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunJ5-8d","jetpack-related-posts":[{"id":445,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/05\/05\/semana-academica-em-lamego-maio-2009\/","url_meta":{"origin":509,"position":0},"title":"Semana Acad\u00e9mica  em Lamego &#8211; Maio 2009","author":"Helena Sebastiana","date":"5 05+00:00 Maio 05+00:00 2009","format":false,"excerpt":"Come\u00e7a, amanh\u00e3, quarta-feira, dia 6 de Maio, mais uma semana acad\u00e9mica em Lamego e terminar\u00e1 segunda-feira, dia 11 de Maio. Est\u00e3o \u00e0 venda na Associa\u00e7\u00e3o de Estudantes da nossa escola pulseiras que d\u00e3o acesso ao recinto todos os dias, pelo valor de 16 \u20ac ou 20 \u20ac. Esta \u00faltima pulseira\u2026","rel":"","context":"In &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/eventos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":391,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/04\/30\/viagem-de-finalistas-09-by-catia-carolina-e-marina\/","url_meta":{"origin":509,"position":1},"title":"Viagem de Finalistas 09 &#8211; By C\u00e1tia, Carolina e Marina!","author":"Helena Sebastiana","date":"30 30+00:00 Abril 30+00:00 2009","format":false,"excerpt":"Antes de mais agradecemos a correc\u00e7\u00e3o da data. Fomos em Mar\u00e7o, mas n\u00e3o nos import\u00e1vamos de voltar em Maio! Temos, agora, a certeza que existem leitores atentos e que o \u201cnosso\u201d blog merece a melhor das aten\u00e7\u00f5es! Esperamos tamb\u00e9m que tenha ficado, pelo menos, algum conhecimento deste local que visit\u00e1mos.\u2026","rel":"","context":"In &quot;Finalistas&quot;","block_context":{"text":"Finalistas","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/finalistas\/"},"img":{"alt_text":"dsc00187","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/ap12a2008\/files\/2009\/04\/dsc00187-300x224.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":303,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/02\/26\/desfile-de-mascaras-e-disfarces\/","url_meta":{"origin":509,"position":2},"title":"Desfile de m\u00e1scaras e disfarces","author":"Helena Sebastiana","date":"26 26+00:00 Fevereiro 26+00:00 2009","format":false,"excerpt":"Na sexta-feira, dia 20, por volta das 15:30 horas deu-se in\u00edcio ao concurso de m\u00e1scaras e disfarces. Foi apresentado por dois alunos do 12.\u00ba ano, Tiago Silva e Joana Coelho. Participaram alunos desde o 5.\u00ba ano at\u00e9 ao 9.\u00ba ano de escolaridade. Cada turma tinha o seu tema de disfarce.\u2026","rel":"","context":"In &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/eventos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":219,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/01\/08\/clube-espaco-arte\/","url_meta":{"origin":509,"position":3},"title":"Clube Espa\u00e7o Arte","author":"Helena Sebastiana","date":"8 08+00:00 Janeiro 08+00:00 2009","format":false,"excerpt":"Segundo o professor Jo\u00e3o Aur\u00e9lio, este clube, criado no ano lectivo anterior, pretende despertar a criatividade dos alunos, visando a cria\u00e7\u00e3o pr\u00f3pria de obras de arte. Este clube destina-se ao segundo ciclo de escolaridade. Est\u00e3o inscritos 18 alunos, divididos em dois turnos. 12 alunos frequentam o clube \u00e0 segunda-feira e\u2026","rel":"","context":"In &quot;Clubes&quot;","block_context":{"text":"Clubes","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/clubes\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":153,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2008\/12\/09\/adesao-total-a-greve-do-dia-3-de-dezembro\/","url_meta":{"origin":509,"position":4},"title":"Ades\u00e3o total \u00e0 greve do dia 3 de Dezembro","author":"Helena Sebastiana","date":"9 09+00:00 Dezembro 09+00:00 2008","format":false,"excerpt":"No dia 3 de Dezembro de 2008, quarta-feira, estava convocada uma greve nacional. Os professores do nosso Agrupamento, como forma de manifestar a sua indigna\u00e7\u00e3o face ao actual modelo de avalia\u00e7\u00e3o, aderiram todos \u00e0 greve. Neste dia, n\u00e3o houve aulas para ningu\u00e9m!","rel":"","context":"In &quot;Eventos&quot;","block_context":{"text":"Eventos","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/eventos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":311,"url":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/2009\/03\/10\/visita-de-estudo-a-aveiro-10%c2%ba-ano\/","url_meta":{"origin":509,"position":5},"title":"Visita de estudo a Aveiro \u2013 10.\u00ba Ano","author":"Helena Sebastiana","date":"10 10+00:00 Mar\u00e7o 10+00:00 2009","format":false,"excerpt":"Na passada sexta-feira, dia 6 de Mar\u00e7o, as turmas A, B e C do d\u00e9cimo ano realizaram uma visita de estudo a Aveiro com o intuito de visitar as dunas de S\u00e3o Jacinto e a F\u00e1brica da Ci\u00eancia Viva. Pelas not\u00edcias que nos chegaram, os objectivos foram plenamente atingidos e\u2026","rel":"","context":"In &quot;Viagens de estudo&quot;","block_context":{"text":"Viagens de estudo","link":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/category\/viagens-de-estudo\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/posts\/509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/comments?post=509"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/posts\/509\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/media?parent=509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/categories?post=509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/ap12a2008\/wp-json\/wp\/v2\/tags?post=509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}