{"id":32,"date":"2009-03-30T22:17:50","date_gmt":"2009-03-30T22:17:50","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/cadernovirtual\/?p=32"},"modified":"2024-06-03T21:37:29","modified_gmt":"2024-06-03T21:37:29","slug":"diario-de-bordo-de-vasco-da-gama","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/cadernovirtual\/2009\/03\/30\/diario-de-bordo-de-vasco-da-gama\/","title":{"rendered":"Di\u00e1rio de bordo de Vasco da Gama"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"right\">22 de Novembro de 1497<\/p>\n<p>Hoje conclu\u00edmos mais uma etapa da nossa viagem; dobr\u00e1mos o Cabo das Tormentas, ou Cabo da Boa Esperan\u00e7a, como D. Jo\u00e3o II lhe chamou quando Bartolomeu Dias passou por l\u00e1.<\/p>\n<p>Est\u00e1vamos a dez l\u00e9guas, quando uma nuvem enorme e escura se p\u00f4s por cima das nossas cabe\u00e7as. Temi, ali, o fim da nossa viagem; temi a morte, confesso. N\u00e3o esper\u00e1vamos tal coisa. Fic\u00e1mos muito apavorados, sem saber o que fazer. Uns rezavam, outros gritavam e previam o pior. Eu, no fundo, estava como eles, mas tentei manter a calma e reagir.<\/p>\n<p>Entretanto, apareceu uma figura monstruosa que se pronunciou. Senti que era o nosso fim, senti o meu cora\u00e7\u00e3o com batimentos mais fortes. Mas ouvi-o e questionei a sua identifica\u00e7\u00e3o. Ele, admirado com o meu acto, mudou o tom de voz e respondeu \u00e0 minha pergunta. Contou, tamb\u00e9m, a sua hist\u00f3ria de amor, com um discurso bastante emotivo: durante a guerra conta J\u00fapiter, Adamastor apaixonou-se por T\u00e9tis, filha de D\u00f3ris. Mas, sabendo que ela nunca o amaria, decidiu conquist\u00e1-la \u00e0 for\u00e7a. Alertada e apoiada pela m\u00e3e, T\u00e9tis marcou um encontro com Adamastor. Por\u00e9m, o encontro n\u00e3o passou de uma armadilha, e o gigante acabou por ficar abra\u00e7ado a um penedo, quando pensava que estava a abra\u00e7ar a sua amada. Profundamente humilhado, o gigante converteu-se num penedo. Sem mais nada a fazer, come\u00e7ou a chorar cada vez mais e deixou-nos seguir o nosso caminho.<\/p>\n<p>\u00c9 de noite e est\u00e1 tudo calmo por aqui. Temi a morte hoje, mais do que nunca, confesso. O que pass\u00e1mos hoje n\u00e3o nos abalou fortaleceu-nos ainda mais. Agora, falta apenas um pequeno peda\u00e7o de mar para a \u00cdndia. Eu sei que um dia l\u00e1 vamos chegar, eu sei que sim!<span style=\"font-size: small; font-family: Calibri;\">\u00a0<\/span><\/p>\n<p style=\"text-align: left;\" align=\"right\">Sem mais nada a acrescentar,<br \/>\n<em>Vasco da Gama<\/em><\/p>\n<p align=\"right\">Mariana Amaral<\/p>\n","protected":false},"excerpt":{"rendered":"<p>22 de Novembro de 1497 Hoje conclu\u00edmos mais uma etapa da nossa viagem; dobr\u00e1mos o Cabo das Tormentas, ou Cabo da Boa Esperan\u00e7a, como D. Jo\u00e3o II lhe chamou quando Bartolomeu Dias passou por l\u00e1. Est\u00e1vamos a dez l\u00e9guas, quando uma nuvem enorme e escura se p\u00f4s por cima das nossas cabe\u00e7as. Temi, ali, o [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[108],"tags":[],"class_list":["post-32","post","type-post","status-publish","format-standard","hentry","category-os-lusiadas"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunIc-w","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/cadernovirtual\/wp-json\/wp\/v2\/posts\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/cadernovirtual\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/cadernovirtual\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/cadernovirtual\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/cadernovirtual\/wp-json\/wp\/v2\/comments?post=32"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/cadernovirtual\/wp-json\/wp\/v2\/posts\/32\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/cadernovirtual\/wp-json\/wp\/v2\/media?parent=32"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/cadernovirtual\/wp-json\/wp\/v2\/categories?post=32"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/cadernovirtual\/wp-json\/wp\/v2\/tags?post=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}