{"id":133,"date":"2009-05-16T11:10:24","date_gmt":"2009-05-16T11:10:24","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/?p=133"},"modified":"2018-12-05T17:56:42","modified_gmt":"2018-12-05T17:56:42","slug":"conheca-a-escola-de-varzea","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2009\/05\/16\/conheca-a-escola-de-varzea\/","title":{"rendered":"Conhe\u00e7a a Escola de V\u00e1rzea"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Este trabalho foi feito no Photosynth a partir de doze fotografias da nossa escola.<\/p>\n<p>Veja: <a href=\"http:\/\/photosynth.net\/view.aspx?cid=6ecd0eed-7a1a-4b32-afe1-37fd3e1e7096\" target=\"_blank\" rel=\"noopener\">Conhe\u00e7a a Escola de V\u00e1rzea de Abrunhais<\/a><\/p>\n<p><a href=\"http:\/\/photosynth.net\/view.aspx?cid=6ecd0eed-7a1a-4b32-afe1-37fd3e1e7096\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\" alignnone\" src=\"http:\/\/photosynth.net\/inc\/images\/master\/logo.gif\" alt=\"Escola de V\u00e1rzea de Abrunhais\" width=\"223\" height=\"51\" \/><\/a><\/p>\n<p><em>Rui Filipe<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Este trabalho foi feito no Photosynth a partir de doze fotografias da nossa escola. Veja: Conhe\u00e7a a Escola de V\u00e1rzea de Abrunhais Rui Filipe &nbsp;<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-133","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunHC-29","jetpack-related-posts":[{"id":206,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2010\/01\/24\/pais-escola-portuguesa-considerada-pela-microsoft-uma-das-escolas-tecnologicamente-mais-inovadora-do-mundo-rtp-noticias-video\/","url_meta":{"origin":133,"position":0},"title":"Pa\u00eds &#8211; Escola portuguesa considerada pela Microsoft uma das escolas tecnologicamente mais Inovadora do Mundo &#8211; RTP Not\u00edcias, V\u00eddeo","author":"admin","date":"Domingo, 24 Janeiro 2010","format":false,"excerpt":"Escola portuguesa considerada pela Microsoft uma das escolas tecnologicamente mais Inovadora do Mundo - RTP Not\u00edcias, V\u00eddeo Conhe\u00e7a agora a Escola do 1.\u00ba Ciclo da pequena aldeia de V\u00e1rzea de Abrunhais, no concelho de Lamego. 2010-01-24 21:00:12 \u00a0 \u00a0 via Pa\u00eds - Escola portuguesa considerada pela Microsoft uma das escolas\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":293,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2010\/06\/06\/293\/","url_meta":{"origin":133,"position":1},"title":"Poesia","author":"M.\u00aa Carmo Leit\u00e3o","date":"Domingo, 6 Junho 2010","format":false,"excerpt":"O Magalh\u00e3es Quando o Magalh\u00e3es chegou Nem queria acreditar Quantas coisas interessantes N\u00f3s pod\u00edamos praticar. De casa para a escola Da escola para casa O Magalh\u00e3es sempre a nos acompanhar Junto da nossa sacola. Come\u00e7\u00e1mos com pequenas brincadeiras Interessantes para trabalhar Continu\u00e1mos na escola Com o Magalh\u00e3es sempre a inovar.\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2010\/06\/image_nmg_1.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":470,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2011\/04\/01\/a-nossa-sala\/","url_meta":{"origin":133,"position":2},"title":"A Nossa Sala","author":"M.\u00aa Carmo Leit\u00e3o","date":"Sexta-feira, 1 Abril 2011","format":false,"excerpt":"\u00a0 A sala Inovadora da Professora Maria do Carmo come\u00e7ou em V\u00e1rzea de Abrunhais quando concorreram a um concurso para ver qual era a escola mais Inovadora do pa\u00eds. Mas passado um ano, muito divertido, a escola do primeiro ciclo fechou portas. Os alunos da sala da Professora Maria do\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2011\/04\/001-300x218.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":727,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2009\/10\/16\/programa-das-escolas-inovadoras-promovido-pela-microsoft-a-nivel-internacional-distingue-duas-escolas-de-portugal\/","url_meta":{"origin":133,"position":3},"title":"Programa das Escolas Inovadoras promovido pela Microsoft a n\u00edvel internacional distingue duas escolas de Portugal","author":"admin","date":"Sexta-feira, 16 Outubro 2009","format":false,"excerpt":"Em Julho de 2009 foi lan\u00e7ado um convite \u00e0s escolas Portuguesas para integrar a rede mundial da Microsoft Escolas Inovadoras. Sugiram duas candidaturas a n\u00edvel nacional, uma da escola EB1 de V\u00e1rzea de Abrunhais liderada pela Professora Maria do Carmo Leit\u00e3o e outra da escola EB2\/3 de Nevogilde - Lousada,\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":105,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2009\/03\/13\/%e2%80%9c-magalhaes-na-escola%e2%80%9d\/","url_meta":{"origin":133,"position":4},"title":"\u201cMagalh\u00e3es&#8221; na Escola","author":"M.\u00aa Carmo Leit\u00e3o","date":"Sexta-feira, 13 Mar\u00e7o 2009","format":false,"excerpt":"\u00a0 Os alunos do 1.\u00ba e 2.\u00ba ano de V\u00e1rzea de Abrunhais iniciaram, na escola, o uso dos seus computadores Magalh\u00e3es. Trabalharam com o programa Photo Story 3 for Windows. Elaboraram um pequeno v\u00eddeo com um trabalho feito no \u00e2mbito do PNEP \u201cO Bicharoco que era Oco\u201d, uma actividade de\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":53,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2008\/10\/19\/entrega-do-livro\/","url_meta":{"origin":133,"position":5},"title":"Entrega do Livro","author":"M.\u00aa Carmo Leit\u00e3o","date":"Domingo, 19 Outubro 2008","format":false,"excerpt":"Entrega do Livro Na sexta feira, dia 27 de Setembro, realizou-se a entrega de um livro a todos os alunos do primeiro ano da escola de V\u00e1rzea de Abrunhais. Foi uma iniciativa do Minist\u00e9rio da Educa\u00e7\u00e3o para que as crian\u00e7as se habituem a ler desde muito cedo. Todos os alunos\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/farm4.static.flickr.com\/3065\/2956245336_83e337b990.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts\/133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/comments?post=133"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts\/133\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/media?parent=133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/categories?post=133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/tags?post=133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}