{"id":36,"date":"2008-04-19T18:31:03","date_gmt":"2008-04-19T18:31:03","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2008\/04\/19\/a-centopeia\/"},"modified":"2009-11-02T01:51:40","modified_gmt":"2009-11-02T01:51:40","slug":"a-centopeia","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2008\/04\/19\/a-centopeia\/","title":{"rendered":"A Centopeia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/bp3.blogger.com\/_wpcDExEvat8\/R9bzFQlO16I\/AAAAAAAAAcE\/hxL-q_YtOAE\/s200\/pnl.jpg\" alt=\"\" width=\"96\" height=\"75\" align=\"left\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/bp3.blogger.com\/_wpcDExEvat8\/R9bzEQlO14I\/AAAAAAAAAb0\/sC8JAD-SM8M\/s200\/hist%C3%B3rias+pequenas+de+bichos+pequenos.jpg\" alt=\"\" width=\"104\" height=\"104\" align=\"middle\" \/> <img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/bp2.blogger.com\/_wpcDExEvat8\/R9bzFAlO15I\/AAAAAAAAAb8\/NIKr08SCNd8\/s200\/images%5B1%5D.jpg\" alt=\"\" width=\"132\" height=\"97\" \/><\/p>\n<p><strong>Trabalh\u00e1mos a produ\u00e7\u00e3o de um texto, assegurando a mobiliza\u00e7\u00e3o de conhecimentos pr\u00e9vios e a sua articula\u00e7\u00e3o com novas informa\u00e7\u00f5es.<\/strong>.<br \/>\n<strong>(1.\u00ba ano)<\/strong><\/p>\n<p><strong>Depois de pesquisar sobre a vida da centopeia,os alunos fizeram esta chuva de ideias.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm4.static.flickr.com\/3250\/2425540950_4ed0d5debd.jpg?v=1208628952\" alt=\"\" width=\"475\" height=\"364\" \/><\/p>\n<p style=\"text-align: left\"><strong>1- Leitura colectiva do texto:<br \/>\n<\/strong><\/p>\n<p style=\"text-align: center\">A centopeia<\/p>\n<p>Era uma vez uma centopeia muito simp\u00e1tica que eu conheci nas f\u00e9rias. Convidei-a para jantar mas ela nunca aparecia. Quando acabava de apertar os cord\u00f5es do cent\u00e9simo sapato do cent\u00e9simo p\u00e9, j\u00e1 eram horas de come\u00e7ar a desapertar os do primeiro para se ir deitar.<br \/>\nUm problema! Quando cal\u00e7ava s\u00f3 cinquenta sapatos tinha tempo de sair para tomar um caf\u00e9 ou um sorvete; mas nesses casos, como ela mesmo dizia, lamentando-se, n\u00e3o passava de uma cinquentopeia.<br \/>\nUma vez passei por ela na rua e era uma quarenta-e-setepeia. Ia t\u00e3o envergonhada que eu fiz de conta que n\u00e3o a vi.<\/p>\n<p align=\"right\">&#8220;Hist\u00f3rias pequenas de bichos pequenos&#8221;<\/p>\n<p align=\"right\">\u00c1lvaro Magalh\u00e3es<\/p>\n<p>Em seguida, organizaram as ideias e escreveram um pequeno texto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/farm3.static.flickr.com\/2110\/2424721529_d5d872fd85.jpg?v=0\" alt=\"\" width=\"463\" height=\"678\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trabalh\u00e1mos a produ\u00e7\u00e3o de um texto, assegurando a mobiliza\u00e7\u00e3o de conhecimentos pr\u00e9vios e a sua articula\u00e7\u00e3o com novas informa\u00e7\u00f5es.. (1.\u00ba ano) Depois de pesquisar sobre a vida da centopeia,os alunos fizeram esta chuva de ideias. 1- Leitura colectiva do texto: A centopeia Era uma vez uma centopeia muito simp\u00e1tica que eu conheci nas f\u00e9rias. Convidei-a [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-36","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunHC-A","jetpack-related-posts":[{"id":39,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2008\/05\/12\/dimensao-textual\/","url_meta":{"origin":36,"position":0},"title":"Dimens\u00e3o Textual","author":"M.\u00aa Carmo Leit\u00e3o","date":"Segunda-feira, 12 Maio 2008","format":false,"excerpt":"O Ensino da Escrita Constru\u00e7\u00e3o de um texto narrativo a partir de um conjunto de imagens. 1.\u00ba Distribuiu-se pelos alunos um conjunto de imagens. 2.\u00ba Em seguida deu-se uma grelha para planificar a estrutura do texto .(1.\u00ba e 4.\u00baano) 3.\u00ba Depois das grelhas preenchidas os alunos escreveram os textos. Os\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/bp2.blogger.com\/_wpcDExEvat8\/R9bzFAlO15I\/AAAAAAAAAb8\/NIKr08SCNd8\/s200\/images%5B1%5D.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":37,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2008\/04\/29\/a-chuva\/","url_meta":{"origin":36,"position":1},"title":"A Chuva","author":"M.\u00aa Carmo Leit\u00e3o","date":"Ter\u00e7a-feira, 29 Abril 2008","format":false,"excerpt":"O Ensino da Escrita: O processo da escrita e suas componentes Ciclo de escrita \u00a0 Objectivo: Trabalhar a produ\u00e7\u00e3o de um texto, assegurando a mobiliza\u00e7\u00e3o de conhecimentos pr\u00e9vios e a sua articula\u00e7\u00e3o com novas informa\u00e7\u00f5es; Tema: A chuva Ano de escolaridade: 1.\u00ba Ano 1.\u00ba Mobiliza\u00e7\u00e3o de conhecimentos 2.\u00ba Recolha e\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/bp2.blogger.com\/_wpcDExEvat8\/R9bzFAlO15I\/AAAAAAAAAb8\/NIKr08SCNd8\/s200\/images%5B1%5D.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":31,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2008\/04\/09\/joaninha\/","url_meta":{"origin":36,"position":2},"title":"joaninha","author":"M.\u00aa Carmo Leit\u00e3o","date":"Quarta-feira, 9 Abril 2008","format":false,"excerpt":"Na explora\u00e7\u00e3o do livro \"Hist\u00f3rias pequenas de bichos pequenos\", de \u00c1lvaro Magalh\u00e3es, obra destacada no Plano Nacional de Leitura e o Programa Nacional de Ensino do Portugu\u00eas, com o objectivo central de melhorar as pr\u00e1ticas pedag\u00f3gicas na \u00e1rea da l\u00edngua materna, trabalhamos o 1\u00baconto \u201cjoaninha\u201d Os alunos do 1\u00ba Ano\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/bp3.blogger.com\/_wpcDExEvat8\/R9bzFQlO16I\/AAAAAAAAAcE\/hxL-q_YtOAE\/s200\/pnl.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":105,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2009\/03\/13\/%e2%80%9c-magalhaes-na-escola%e2%80%9d\/","url_meta":{"origin":36,"position":3},"title":"\u201cMagalh\u00e3es&#8221; na Escola","author":"M.\u00aa Carmo Leit\u00e3o","date":"Sexta-feira, 13 Mar\u00e7o 2009","format":false,"excerpt":"\u00a0 Os alunos do 1.\u00ba e 2.\u00ba ano de V\u00e1rzea de Abrunhais iniciaram, na escola, o uso dos seus computadores Magalh\u00e3es. Trabalharam com o programa Photo Story 3 for Windows. Elaboraram um pequeno v\u00eddeo com um trabalho feito no \u00e2mbito do PNEP \u201cO Bicharoco que era Oco\u201d, uma actividade de\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":53,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2008\/10\/19\/entrega-do-livro\/","url_meta":{"origin":36,"position":4},"title":"Entrega do Livro","author":"M.\u00aa Carmo Leit\u00e3o","date":"Domingo, 19 Outubro 2008","format":false,"excerpt":"Entrega do Livro Na sexta feira, dia 27 de Setembro, realizou-se a entrega de um livro a todos os alunos do primeiro ano da escola de V\u00e1rzea de Abrunhais. Foi uma iniciativa do Minist\u00e9rio da Educa\u00e7\u00e3o para que as crian\u00e7as se habituem a ler desde muito cedo. Todos os alunos\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/farm4.static.flickr.com\/3065\/2956245336_83e337b990.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2008\/03\/14\/a-nossa-comunhao-pascal\/","url_meta":{"origin":36,"position":5},"title":"A nossa Comunh\u00e3o Pascal","author":"M.\u00aa Carmo Leit\u00e3o","date":"Sexta-feira, 14 Mar\u00e7o 2008","format":false,"excerpt":"Comunh\u00e3o Pascal A Comunh\u00e3o Pascal foi uma cerim\u00f3nia bonita, celebrada \u00e0s 11h 00m, por dois padres, na nossa escola. Primeiro, vieram os padres para nos confessar. A Beatriz leu um pequeno texto e mostrou o seu sorriso. Cant\u00e1mos lindas m\u00fasicas com gestos. Os brinquedos que n\u00f3s temos n\u00e3o s\u00e3o s\u00f3\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/farm3.static.flickr.com\/2193\/2333291310_5cf78e3daf_m.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/comments?post=36"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts\/36\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/media?parent=36"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/categories?post=36"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/tags?post=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}