{"id":447,"date":"2011-02-10T22:22:37","date_gmt":"2011-02-10T22:22:37","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/?p=447"},"modified":"2018-12-05T02:12:54","modified_gmt":"2018-12-05T02:12:54","slug":"o-dia-intrenacional-de-braille","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2011\/02\/10\/o-dia-intrenacional-de-braille\/","title":{"rendered":"O dia Intrenacional de Braille"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><!--YouTube Error: bad URL entered--><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp;<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-447","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunHC-7d","jetpack-related-posts":[{"id":437,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2011\/01\/07\/o-dia-de-s-martinho-2\/","url_meta":{"origin":447,"position":0},"title":"O dia de S. Martinho","author":"M.\u00aa Carmo Leit\u00e3o","date":"Sexta-feira, 7 Janeiro 2011","format":false,"excerpt":"\u00a0 \u00a0","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":563,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2011\/10\/31\/o-dia-das-bruxas\/","url_meta":{"origin":447,"position":1},"title":"O dia das Bruxas","author":"M.\u00aa Carmo Leit\u00e3o","date":"Segunda-feira, 31 Outubro 2011","format":false,"excerpt":"\u00a0 \u00a0 \u00a0","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":413,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2010\/12\/03\/dia-internacional-das-pessoas-portadoras-de-deficiencia\/","url_meta":{"origin":447,"position":2},"title":"Dia internacional das pessoas portadoras de defici\u00eancia","author":"M.\u00aa Carmo Leit\u00e3o","date":"Sexta-feira, 3 Dezembro 2010","format":false,"excerpt":"\u00a0 \u00a0 \u00a0 D ia de amizade E duca\u00e7\u00e3o especial F or\u00e7a devemos dar I ncluir no nosso grupo C om carinho, amor e amizade I mportante \u00e9 o seu caminho E stes meninos N \u00e3o devemos rejeitar C om cuidados redobrados I guais mas diferentes A todos devemos respeitar\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2010\/12\/Educa%C3%A7%C3%A3o-especial1-226x300.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":363,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2010\/10\/20\/o-dia-da-musica\/","url_meta":{"origin":447,"position":3},"title":"O Dia da M\u00fasica","author":"M.\u00aa Carmo Leit\u00e3o","date":"Quarta-feira, 20 Outubro 2010","format":false,"excerpt":"\u00a0 \u00a0","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":512,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2011\/05\/05\/o-dia-da-poesia\/","url_meta":{"origin":447,"position":4},"title":"O dia da Poesia","author":"M.\u00aa Carmo Leit\u00e3o","date":"Quinta-feira, 5 Maio 2011","format":false,"excerpt":"\u00a0 \u00a0","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":246,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2010\/03\/24\/o-dia-do-pai-2\/","url_meta":{"origin":447,"position":5},"title":"O dia do PAI","author":"M.\u00aa Carmo Leit\u00e3o","date":"Quarta-feira, 24 Mar\u00e7o 2010","format":false,"excerpt":"\u00a0 \u00a0","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts\/447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/comments?post=447"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts\/447\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/media?parent=447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/categories?post=447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/tags?post=447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}