{"id":470,"date":"2011-04-01T11:11:09","date_gmt":"2011-04-01T11:11:09","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/?p=470"},"modified":"2018-12-05T02:06:26","modified_gmt":"2018-12-05T02:06:26","slug":"a-nossa-sala","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2011\/04\/01\/a-nossa-sala\/","title":{"rendered":"A Nossa Sala"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>A sala Inovadora da Professora Maria do Carmo come\u00e7ou em V\u00e1rzea de Abrunhais quando concorreram a um concurso para ver qual era a escola mais Inovadora do pa\u00eds.<\/strong><\/p>\n<p><strong> Mas passado um ano, muito divertido, a escola do primeiro ciclo fechou portas.<\/strong><\/p>\n<p><strong>Os alunos da sala da Professora Maria do Carmo vieram para uma nova escola que se chama Centro Escolar Lamego \u2013 Sudeste. <\/strong><\/p>\n<p><strong>Chegaram \u00e0 nova escola e ficaram espantados com a beleza da sala e do seu pavilh\u00e3o.<\/strong><\/p>\n<p><strong>Vieram novos alunos, que eram 5. Vieram de uma escola muito diferente, que nunca mexiam nos Magalh\u00e3es, e eles aprenderam coisas novas e a respeitar.<\/strong><\/p>\n<p><strong>N\u00f3s adoramos andar aqui, nesta escola fant\u00e1stica com os nossos colegas!<\/strong><\/p>\n<p><strong>A sala Inovadora da Professora Maria do Carmo come\u00e7ou em V\u00e1rzea de Abrunhais quando concorreram a um concurso para ver qual era a escola mais Inovadora do pa\u00eds.<\/strong><\/p>\n<p><strong> Mas passado um ano, muito divertido, a escola do primeiro ciclo fechou portas.<\/strong><\/p>\n<p><strong>Os alunos da sala da Professora Maria do Carmo vieram para uma nova escola que se chama Centro Escolar Lamego \u2013 Sudeste. <\/strong><\/p>\n<p><strong>Chegaram \u00e0 nova escola e ficaram espantados com a beleza da sala e do seu pavilh\u00e3o.<\/strong><\/p>\n<p><strong>Vieram novos alunos, que eram 5. Vieram de uma escola muito diferente, que nunca mexiam nos Magalh\u00e3es, e eles aprenderam coisas novas e a respeitar.<\/strong><\/p>\n<p><strong>N\u00f3s adoramos andar aqui, nesta escola fant\u00e1stica com os nossos colegas!<\/strong><\/p>\n<p>Joel Paiva<\/p>\n<p>3\u00ba4\u00baC<\/p>\n<p>Educa\u00e7\u00e3o Especial<\/p>\n<p><a href=\"http:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2011\/04\/001.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"471\" data-permalink=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2011\/04\/01\/a-nossa-sala\/attachment\/001\/\" data-orig-file=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2011\/04\/001.jpg\" data-orig-size=\"2338,1700\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"A SALA INOVADORA\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2011\/04\/001-1024x744.jpg\" class=\"size-medium wp-image-471 alignnone aligncenter\" src=\"http:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2011\/04\/001-300x218.jpg\" alt=\"\" width=\"523\" height=\"380\" srcset=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2011\/04\/001-300x218.jpg 300w, https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2011\/04\/001-1024x744.jpg 1024w\" sizes=\"auto, (max-width: 523px) 100vw, 523px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; A sala Inovadora da Professora Maria do Carmo come\u00e7ou em V\u00e1rzea de Abrunhais quando concorreram a um concurso para ver qual era a escola mais Inovadora do pa\u00eds. Mas passado um ano, muito divertido, a escola do primeiro ciclo fechou portas. Os alunos da sala da Professora Maria do Carmo vieram para uma nova [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-470","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunHC-7A","jetpack-related-posts":[{"id":218,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2010\/02\/12\/uma-das-escolas-mais-avancadas-do-mundo-e-portuguesa-visao-pt\/","url_meta":{"origin":470,"position":0},"title":"Uma das escolas mais avan\u00e7adas do mundo \u00e9 portuguesa &#8211; Visao.pt","author":"admin","date":"Sexta-feira, 12 Fevereiro 2010","format":false,"excerpt":"Uma das escolas mais avan\u00e7adas do mundo \u00e9 portuguesa Sabe onde fica V\u00e1rzea de Abrunhais? Se n\u00e3o sabe, devia. Foi nesta freguesia, dos arredores de Lamego, que a Microsoft encontrou uma das melhores escolas, no mundo, a aplicar novas tecnologias na aprendizagem. Mario David Campos (texto) e Luc\u00edlia Monteiro (fotos)\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ea.ess-edu.pt\/wp-content\/uploads\/2010\/02\/visao-vabrunhais-300x199.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":293,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2010\/06\/06\/293\/","url_meta":{"origin":470,"position":1},"title":"Poesia","author":"M.\u00aa Carmo Leit\u00e3o","date":"Domingo, 6 Junho 2010","format":false,"excerpt":"O Magalh\u00e3es Quando o Magalh\u00e3es chegou Nem queria acreditar Quantas coisas interessantes N\u00f3s pod\u00edamos praticar. De casa para a escola Da escola para casa O Magalh\u00e3es sempre a nos acompanhar Junto da nossa sacola. Come\u00e7\u00e1mos com pequenas brincadeiras Interessantes para trabalhar Continu\u00e1mos na escola Com o Magalh\u00e3es sempre a inovar.\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2010\/06\/image_nmg_1.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":627,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2011\/07\/03\/cartas-de-finalistas\/","url_meta":{"origin":470,"position":2},"title":"Cartas de Finalistas 4\u00baanoC","author":"M.\u00aa Carmo Leit\u00e3o","date":"Domingo, 3 Julho 2011","format":false,"excerpt":"Para a nossa Professora \u00a0 Professora Carmito Professora Carmito Ri muitas vezes, porque \u00e9 feliz O seu olhar d\u00e1-nos alegria Faz belos trabalhos Encontra as nossas fraquezas Sabe muitas coisas Sabe como n\u00f3s gostamos dela O seu cora\u00e7\u00e3o nunca nos esquecer\u00e1 Reencontrar-nos todos os dias Amor n\u00f3s lhe daremos para\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":53,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2008\/10\/19\/entrega-do-livro\/","url_meta":{"origin":470,"position":3},"title":"Entrega do Livro","author":"M.\u00aa Carmo Leit\u00e3o","date":"Domingo, 19 Outubro 2008","format":false,"excerpt":"Entrega do Livro Na sexta feira, dia 27 de Setembro, realizou-se a entrega de um livro a todos os alunos do primeiro ano da escola de V\u00e1rzea de Abrunhais. Foi uma iniciativa do Minist\u00e9rio da Educa\u00e7\u00e3o para que as crian\u00e7as se habituem a ler desde muito cedo. Todos os alunos\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/farm4.static.flickr.com\/3065\/2956245336_83e337b990.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":13,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2008\/03\/14\/a-nossa-comunhao-pascal\/","url_meta":{"origin":470,"position":4},"title":"A nossa Comunh\u00e3o Pascal","author":"M.\u00aa Carmo Leit\u00e3o","date":"Sexta-feira, 14 Mar\u00e7o 2008","format":false,"excerpt":"Comunh\u00e3o Pascal A Comunh\u00e3o Pascal foi uma cerim\u00f3nia bonita, celebrada \u00e0s 11h 00m, por dois padres, na nossa escola. Primeiro, vieram os padres para nos confessar. A Beatriz leu um pequeno texto e mostrou o seu sorriso. Cant\u00e1mos lindas m\u00fasicas com gestos. Os brinquedos que n\u00f3s temos n\u00e3o s\u00e3o s\u00f3\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/farm3.static.flickr.com\/2193\/2333291310_5cf78e3daf_m.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":727,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2009\/10\/16\/programa-das-escolas-inovadoras-promovido-pela-microsoft-a-nivel-internacional-distingue-duas-escolas-de-portugal\/","url_meta":{"origin":470,"position":5},"title":"Programa das Escolas Inovadoras promovido pela Microsoft a n\u00edvel internacional distingue duas escolas de Portugal","author":"admin","date":"Sexta-feira, 16 Outubro 2009","format":false,"excerpt":"Em Julho de 2009 foi lan\u00e7ado um convite \u00e0s escolas Portuguesas para integrar a rede mundial da Microsoft Escolas Inovadoras. Sugiram duas candidaturas a n\u00edvel nacional, uma da escola EB1 de V\u00e1rzea de Abrunhais liderada pela Professora Maria do Carmo Leit\u00e3o e outra da escola EB2\/3 de Nevogilde - Lousada,\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts\/470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/comments?post=470"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts\/470\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/media?parent=470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/categories?post=470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/tags?post=470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}