{"id":81,"date":"2009-02-13T12:52:37","date_gmt":"2009-02-13T12:52:37","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/?p=81"},"modified":"2018-12-05T19:59:43","modified_gmt":"2018-12-05T19:59:43","slug":"o-nosso-natal","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2009\/02\/13\/o-nosso-natal\/","title":{"rendered":"O Nosso Natal"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>A nossa festa de Natal<\/p>\n<p>\u00c0 semelhan\u00e7a dos anos anteriores, a nossa Escola e o Jardim realizaram a festinha de Natal com a preciosa colabora\u00e7\u00e3o dos alunos, dos amigos da escola, da Junta de Freguesia, dos ex-alunos, dos pais, dos professores das AEC&#8217;s e dos professores, educadora e funcion\u00e1rios das duas institui\u00e7\u00f5es.<br \/>\nA todos, o nosso bem-haja pela disponibilidade, pela alegria e pela vontade ENORME de partilhar. Feliz Natal!!!<\/p>\n<p><a href=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2079-1.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"705\" data-permalink=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2009\/02\/13\/o-nosso-natal\/dscf2079-2\/\" data-orig-file=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2079-1.jpg\" data-orig-size=\"1280,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FinePix A310&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1041379242&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.7&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dscf2079\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2079-1-1024x768.jpg\" class=\"alignnone wp-image-705 size-medium\" src=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2079-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2079-1-300x225.jpg 300w, https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2079-1-768x576.jpg 768w, https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2079-1-1024x768.jpg 1024w, https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2079-1.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u00a0<a href=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2081-1.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"706\" data-permalink=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2009\/02\/13\/o-nosso-natal\/dscf2081-2\/\" data-orig-file=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2081-1.jpg\" data-orig-size=\"1280,960\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;FinePix A310&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1041449332&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;17.1&quot;,&quot;iso&quot;:&quot;320&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"dscf2081\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2081-1-1024x768.jpg\" class=\"alignnone wp-image-706 size-medium\" src=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2081-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2081-1-300x225.jpg 300w, https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2081-1-768x576.jpg 768w, https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2081-1-1024x768.jpg 1024w, https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2081-1.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; A nossa festa de Natal \u00c0 semelhan\u00e7a dos anos anteriores, a nossa Escola e o Jardim realizaram a festinha de Natal com a preciosa colabora\u00e7\u00e3o dos alunos, dos amigos da escola, da Junta de Freguesia, dos ex-alunos, dos pais, dos professores das AEC&#8217;s e dos professores, educadora e funcion\u00e1rios das duas institui\u00e7\u00f5es. A todos, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-81","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunHC-1j","jetpack-related-posts":[{"id":218,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2010\/02\/12\/uma-das-escolas-mais-avancadas-do-mundo-e-portuguesa-visao-pt\/","url_meta":{"origin":81,"position":0},"title":"Uma das escolas mais avan\u00e7adas do mundo \u00e9 portuguesa &#8211; Visao.pt","author":"admin","date":"Sexta-feira, 12 Fevereiro 2010","format":false,"excerpt":"Uma das escolas mais avan\u00e7adas do mundo \u00e9 portuguesa Sabe onde fica V\u00e1rzea de Abrunhais? Se n\u00e3o sabe, devia. Foi nesta freguesia, dos arredores de Lamego, que a Microsoft encontrou uma das melhores escolas, no mundo, a aplicar novas tecnologias na aprendizagem. Mario David Campos (texto) e Luc\u00edlia Monteiro (fotos)\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ea.ess-edu.pt\/wp-content\/uploads\/2010\/02\/visao-vabrunhais-300x199.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":42,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2008\/07\/14\/encerramento-do-ano-lectivo\/","url_meta":{"origin":81,"position":1},"title":"Encerramento do ano lectivo","author":"M.\u00aa Carmo Leit\u00e3o","date":"Segunda-feira, 14 Julho 2008","format":false,"excerpt":"\u00a0 O fim do ano escolar \u00e9 sempre festivo, barulhento e divertido. No \u00faltimo dia de aulas houve Festa no P\u00e1tio da Escola onde participaram todos os alunos e professores deste estabelecimento de ensino (Jardim de Inf\u00e2ncia \/ 1.\u00ba ciclo), tamb\u00e9m os professores das Actividades de Enriquecimento Curricular (AEC) e\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/farm4.static.flickr.com\/3157\/2668691949_1c916cfbc3.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":96,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2009\/02\/26\/o-nosso-carnaval\/","url_meta":{"origin":81,"position":2},"title":"O Nosso CARNAVAL","author":"M.\u00aa Carmo Leit\u00e3o","date":"Quinta-feira, 26 Fevereiro 2009","format":false,"excerpt":"\u00a0 Na sexta-feira, dia 19 de Fevereiro, a Escola EB1 e o Jardim de Inf\u00e2ncia festejaram o Carnaval, revivendo o Entrudo de outros tempos. Com esta iniciativa, a escola visou reviver tradi\u00e7\u00f5es e costumes antigos. Nesse dia, os alunos vieram para a escola com disfarces encontrados nos ba\u00fas: roupas dos\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2009\/02\/dscf2178-1-150x150.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":382,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2010\/11\/20\/a-nova-escola-vista-por-nos\/","url_meta":{"origin":81,"position":3},"title":"A Nova Escola Vista por N\u00f3s","author":"M.\u00aa Carmo Leit\u00e3o","date":"S\u00e1bado, 20 Novembro 2010","format":false,"excerpt":"Palavra puxa palavra A nova escola \u00e9 muito colorida, Colorida e espa\u00e7osa Espa\u00e7osa \u00e9 a nossa sala. Sala onde estudamos, Estudamos nos livros, Livros novos e diferentes. Novos amigos com quem brincamos Brincamos no recreio, Recreio onde h\u00e1 baloi\u00e7os, Baloi\u00e7os e escorregas, Escorregas variados. Variados s\u00e3o nas suas cores, Cores\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/farm5.static.flickr.com\/4091\/5193311834_6dd888f9ec_m.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":53,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2008\/10\/19\/entrega-do-livro\/","url_meta":{"origin":81,"position":4},"title":"Entrega do Livro","author":"M.\u00aa Carmo Leit\u00e3o","date":"Domingo, 19 Outubro 2008","format":false,"excerpt":"Entrega do Livro Na sexta feira, dia 27 de Setembro, realizou-se a entrega de um livro a todos os alunos do primeiro ano da escola de V\u00e1rzea de Abrunhais. Foi uma iniciativa do Minist\u00e9rio da Educa\u00e7\u00e3o para que as crian\u00e7as se habituem a ler desde muito cedo. Todos os alunos\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/farm4.static.flickr.com\/3065\/2956245336_83e337b990.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":470,"url":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/2011\/04\/01\/a-nossa-sala\/","url_meta":{"origin":81,"position":5},"title":"A Nossa Sala","author":"M.\u00aa Carmo Leit\u00e3o","date":"Sexta-feira, 1 Abril 2011","format":false,"excerpt":"\u00a0 A sala Inovadora da Professora Maria do Carmo come\u00e7ou em V\u00e1rzea de Abrunhais quando concorreram a um concurso para ver qual era a escola mais Inovadora do pa\u00eds. Mas passado um ano, muito divertido, a escola do primeiro ciclo fechou portas. Os alunos da sala da Professora Maria do\u2026","rel":"","context":"In &quot;Sem categoria&quot;","block_context":{"text":"Sem categoria","link":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/category\/sem-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/eb1vabrunhais\/files\/2011\/04\/001-300x218.jpg?resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts\/81","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/comments?post=81"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/posts\/81\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/media?parent=81"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/categories?post=81"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/eb1vabrunhais\/wp-json\/wp\/v2\/tags?post=81"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}