{"id":172,"date":"2008-06-08T15:08:39","date_gmt":"2008-06-08T14:08:39","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/informese\/2008\/06\/08\/o-nosso-projecto-3\/"},"modified":"2008-06-08T15:10:59","modified_gmt":"2008-06-08T14:10:59","slug":"o-nosso-projecto-3","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/informese\/2008\/06\/08\/o-nosso-projecto-3\/","title":{"rendered":"O nosso projecto&#8230;"},"content":{"rendered":"<p>No in\u00edcio do ano, todos opt\u00e1mos por seguir a sugest\u00e3o da professora: criar um jornal online. Parecia f\u00e1cil no in\u00edcio, mas veio a revelar-se muito dif\u00edcil trabalharmos em grupo devido \u00e0 diversidade de opini\u00f5es.<\/p>\n<p>Come\u00e7\u00e1mos por realizar inqu\u00e9ritos para saber a opini\u00e3o da comunidade escolar e, consequentemente, a ades\u00e3o que ir\u00edamos ter. Depois de recebermos as respostas aos inqu\u00e9ritos, conclu\u00edmos que era importante e oportuno criar um servidor para que todos pudessem divulgar not\u00edcias e viv\u00eancias importantes. Deste modo e com este projecto, pretend\u00edamos que esta escola fosse uma  \u201cescola ligada, uma escola conectada\u201d.<\/p>\n<p>Toda a comunidade escolar teve a possibilidade de criar o seu blog, tal como n\u00f3s. A partir desta altura, cada um foi respons\u00e1vel pelo seu espa\u00e7o. Desde esse momento, escrevemos muitos artigos,  exactamente cento e trinta e seis, sobre as mais variadas tem\u00e1ticas e sobre os mais diversos assuntos.<\/p>\n<p>Foi uma \u00e1rea diferente, mas t\u00e3o, ou mais importante que as outras. Ajudou-nos a saber lidar em grupo, a trabalhar por nossa iniciativa e a enfrentar os novos obst\u00e1culos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No in\u00edcio do ano, todos opt\u00e1mos por seguir a sugest\u00e3o da professora: criar um jornal online. Parecia f\u00e1cil no in\u00edcio, mas veio a revelar-se muito dif\u00edcil trabalharmos em grupo devido \u00e0 diversidade de opini\u00f5es. Come\u00e7\u00e1mos por realizar inqu\u00e9ritos para saber a opini\u00e3o da comunidade escolar e, consequentemente, a ades\u00e3o que ir\u00edamos ter. Depois de recebermos [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[19,15],"tags":[],"class_list":["post-172","post","type-post","status-publish","format-standard","hentry","category-a-nossa-escola","category-featured"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunGN-2M","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/posts\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/comments?post=172"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/posts\/172\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/media?parent=172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/categories?post=172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/tags?post=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}