{"id":28,"date":"2008-02-18T17:30:22","date_gmt":"2008-02-18T16:30:22","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/informese\/2008\/02\/18\/a-caminho-do-parlamento\/"},"modified":"2008-02-22T23:48:45","modified_gmt":"2008-02-22T22:48:45","slug":"a-caminho-do-parlamento","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/informese\/2008\/02\/18\/a-caminho-do-parlamento\/","title":{"rendered":"A Caminho do Parlamento"},"content":{"rendered":"<p ALIGN=\"justify\">Este ano lectivo foi dada oportunidade aos alunos da escola para participarem como \u201cdeputados\u201d no Parlamento dos Jovens. Como iria haver elei\u00e7\u00f5es, a escola entrou em campanha. O interesse e o empenho dos participantes em ganhar esta primeira batalha foram enormes. O destino seria a Assembleia da Rep\u00fablica. Era uma oportunidade \u00fanica que os candidatos n\u00e3o queriam deixar escapar!<\/p>\n<p ALIGN=\"justify\">Os objectivos, educar para a cidadania, estimulando o gosto pela participa\u00e7\u00e3o c\u00edvica e pol\u00edtica, incentivar a reflex\u00e3o sobre um tema e a participa\u00e7\u00e3o num processo eleitoral, estimular a capacidade de express\u00e3o e argumenta\u00e7\u00e3o, promover o debate democr\u00e1tico, segundo a regras parlamentares e conhecer a Assembleia da Rep\u00fablica e o exerc\u00edcio do mandato de Deputado, parecem-nos ter sido quase todos, plenamente, atingidos.<\/p>\n<p ALIGN=\"justify\">Foram escolhidos para ir ao Parlamento e para representar a nossa escola os alunos Lu\u00eds Carlos Morais, Jo\u00e3o Carlos Calvo Ribeiro e J\u00falia Filipa Mota, do ensino b\u00e1sico. Relativamente, ao ensino secund\u00e1rio, os alunos Leandro Manuel Pereira da Silva, Vitor Marcelo Sousa Teles e Bruna Skarlet Silva foram os seleccionados.<\/p>\n<p ALIGN=\"justify\">Da nossa parte s\u00f3 nos resta desejar boa sorte e esperar que aproveitem, ao m\u00e1ximo, esta experi\u00eancia \u00fanica. Boa Sorte!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este ano lectivo foi dada oportunidade aos alunos da escola para participarem como \u201cdeputados\u201d no Parlamento dos Jovens. Como iria haver elei\u00e7\u00f5es, a escola entrou em campanha. O interesse e o empenho dos participantes em ganhar esta primeira batalha foram enormes. O destino seria a Assembleia da Rep\u00fablica. Era uma oportunidade \u00fanica que os candidatos [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[19],"tags":[],"class_list":["post-28","post","type-post","status-publish","format-standard","hentry","category-a-nossa-escola"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunGN-s","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/posts\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/comments?post=28"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/posts\/28\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/media?parent=28"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/categories?post=28"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/tags?post=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}