{"id":51,"date":"2008-03-03T17:47:00","date_gmt":"2008-03-03T16:47:00","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/informese\/2008\/03\/03\/inauguracao-do-teatro-ribeiro-conceicao\/"},"modified":"2024-06-06T16:42:13","modified_gmt":"2024-06-06T15:42:13","slug":"inauguracao-do-teatro-ribeiro-conceicao","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/informese\/2008\/03\/03\/inauguracao-do-teatro-ribeiro-conceicao\/","title":{"rendered":"Inaugura\u00e7\u00e3o do Teatro Ribeiro Concei\u00e7\u00e3o"},"content":{"rendered":"<p align=\"justify\">No passado dia 23 de Fevereiro foi reinaugurado, pelo nosso Presidente da Rep\u00fablica, o Teatro Ribeiro Concei\u00e7\u00e3o. Inaugurado pela primeira vez a 2 de Fevereiro de 1929, passou a acolher espect\u00e1culos de teatro, \u00f3pera, circo, cinema, dan\u00e7a e m\u00fasica, que o enchiam por completo, tornando Lamego numa refer\u00eancia na vida cultural do interior do pa\u00eds.<\/p>\n<p align=\"justify\">Esta sala espect\u00e1culos, considerada por muitos uma \u201cj\u00f3ia\u201d cultural e patrimonial, voltou a funcionar ap\u00f3s duas d\u00e9cadas. As obras de reabilita\u00e7\u00e3o e moderniza\u00e7\u00e3o tiveram in\u00edcio no final de 2005 e tiveram um custo total de 6,2 milh\u00f5es de euros. A maior sala de espect\u00e1culos da regi\u00e3o duriense est\u00e1 de novo a funcionar, pronta a produzir um profundo impacto na vida cultural da cidade e da regi\u00e3o. As obras consistiram na preserva\u00e7\u00e3o da fachada e na decora\u00e7\u00e3o do interior, &#8220;inspiradas na arquitectura das grandes salas de teatro italianas&#8221; e, simultaneamente, dotando o teatro &#8220;com moderno equipamento audiovisual e sonoro&#8221;.<\/p>\n<p align=\"justify\">Segundo a autarquia, a nova sala de espect\u00e1culos de Lamego tem uma ac\u00fastica perfeita, disponibilizando 470 lugares sentados. Espera-se que, com o in\u00edcio da sua programa\u00e7\u00e3o regular, Lamego preencha a actual escassez de equipamentos culturais. A C\u00e2mara Municipal de Lamego e a empresa Lamego ConVida ser\u00e3o respons\u00e1veis pela programa\u00e7\u00e3o de um cartaz de espect\u00e1culos abarcando \u00e1reas como a m\u00fasica, o teatro, a dan\u00e7a e o cinema, pretendendo com isso criar e satisfazer os diferentes p\u00fablicos.<\/p>\n<p align=\"justify\">O Teatro Ribeiro Concei\u00e7\u00e3o possui, tamb\u00e9m, v\u00e1rios espa\u00e7os complementares, que ser\u00e3o destinados a outras actividades, como por exemplo, exposi\u00e7\u00f5es, congressos e semin\u00e1rios de car\u00e1cter cultural.<\/p>\n<p align=\"justify\">No nosso entender ser\u00e1 uma boa sala para realizar qualquer tipo de espect\u00e1culo. Esperamos, tamb\u00e9m, que este seja um \u201cregresso para ficar\u201d, porque s\u00e3o actividades como estas que Lamego precisa, para voltar a ter o prest\u00edgio cultural que teve em tempos.<\/p>\n<p align=\"justify\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" align=\"left\" width=\"400\" src=\"https:\/\/blogs.ess-edu.pt\/informese\/wp-content\/blogs.dir\/4\/files\/2008\/03\/080223_PR_1449.jpg\" alt=\"080223_PR_1449.jpg\" height=\"266\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No passado dia 23 de Fevereiro foi reinaugurado, pelo nosso Presidente da Rep\u00fablica, o Teatro Ribeiro Concei\u00e7\u00e3o. Inaugurado pela primeira vez a 2 de Fevereiro de 1929, passou a acolher espect\u00e1culos de teatro, \u00f3pera, circo, cinema, dan\u00e7a e m\u00fasica, que o enchiam por completo, tornando Lamego numa refer\u00eancia na vida cultural do interior do pa\u00eds. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[31],"tags":[],"class_list":["post-51","post","type-post","status-publish","format-standard","hentry","category-cultura"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunGN-P","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/posts\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/comments?post=51"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/posts\/51\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/media?parent=51"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/categories?post=51"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/informese\/wp-json\/wp\/v2\/tags?post=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}