{"id":328,"date":"2012-03-19T23:08:17","date_gmt":"2012-03-19T23:08:17","guid":{"rendered":"http:\/\/blogs.ess-edu.pt\/sm2010\/?p=328"},"modified":"2024-06-09T16:52:04","modified_gmt":"2024-06-09T16:52:04","slug":"desafio-da-semana-da-matematica-2012","status":"publish","type":"post","link":"https:\/\/blogs.ess-edu.pt\/sm2010\/2012\/03\/19\/desafio-da-semana-da-matematica-2012\/","title":{"rendered":"Desafio da Semana da Matem\u00e1tica &#8211; 2012"},"content":{"rendered":"<p>O Desafio da Semana da Matem\u00e1tica inclui a resolu\u00e7\u00e3o de um problema, cujo enunciado est\u00e1 numa p\u00e1gina, protegida por uma palavra-chave, do <a href=\"https:\/\/blogs.ess-edu.pt\/sm2010\/\">S\u00edtio com Matem\u00e1tica<\/a> (<a href=\"https:\/\/blogs.ess-edu.pt\/sm2010\/\">https:\/\/blogs.ess-edu.pt\/sm2010\/<\/a>).<\/p>\n<p>A palavra-chave de <a href=\"https:\/\/blogs.ess-edu.pt\/sm2010\/?page_id=295\">acesso ao enunciado<\/a> \u00e9 a solu\u00e7\u00e3o da seguinte quest\u00e3o:<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/blogs.ess-edu.pt\/sm2010\/files\/2010\/03\/enigma13478.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"124\" data-permalink=\"https:\/\/blogs.ess-edu.pt\/sm2010\/desafio-sm\/desafio-da-sm-2010\/enigma13478\/\" data-orig-file=\"https:\/\/blogs.ess-edu.pt\/sm2010\/files\/2010\/03\/enigma13478.jpg\" data-orig-size=\"600,407\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;HP pstc4380&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"enigma13478\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/blogs.ess-edu.pt\/sm2010\/files\/2010\/03\/enigma13478.jpg\" class=\"alignleft wp-image-124 size-medium\" src=\"http:\/\/blogs.ess-edu.pt\/sm2010\/files\/2010\/03\/enigma13478-300x203.jpg\" alt=\"\" width=\"300\" height=\"203\" srcset=\"https:\/\/blogs.ess-edu.pt\/sm2010\/files\/2010\/03\/enigma13478-300x203.jpg 300w, https:\/\/blogs.ess-edu.pt\/sm2010\/files\/2010\/03\/enigma13478.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\n<strong><span style=\"font-size: medium;\">A Palavra-chave<\/span><\/strong><\/p>\n<p><span style=\"font-size: medium;\">Qual \u00e9 o s\u00e9timo termo da sequ\u00eancia<br \/>\n1, 2, 6, 24, 120, 720, _______ ?<\/span><\/p>\n<p><a href=\"https:\/\/web.archive.org\/web\/20200129153653\/http:\/\/www.educ.fc.ul.pt\/icm\/icm99\/icm31\/sequencias.htm\" target=\"_blank\" rel=\"noopener\">Saber o que \u00e9 uma sequ\u00eancia&#8230;<\/a> <a href=\"https:\/\/www.youtube.com\/watch?v=lUA7Kpnr8Bg&amp;t=142s\" target=\"_blank\" rel=\"noopener\">Mais&#8230;<\/a><\/p>\n<p><span style=\"color: #000080;\">A palavra-chave de acesso \u00e0 p\u00e1gina do enunciado do problema \u00e9, portanto, <strong><span style=\"text-decoration: underline;\">o s\u00e9timo termo<\/span><\/strong> da sequ\u00eancia.<\/span><\/p>\n<p><a href=\"https:\/\/blogs.ess-edu.pt\/sm2010\/?page_id=295\">Acesso ao enunciado<\/a><\/p>\n<p style=\"text-align: center;\"><strong>REGULAMENTO<\/strong><\/p>\n<ol>\n<li>Este desafio realiza-se no \u00e2mbito da Semana da Matem\u00e1tica, sendo respons\u00e1veis os professores Ant\u00f3nio Amaral e Filipe Ferraz.<\/li>\n<li>A participa\u00e7\u00e3o est\u00e1 aberta aos alunos do 2.\u00ba e 3.\u00ba Ciclos do Ensino B\u00e1sico e Ensino Secund\u00e1rio da Escola Secund\u00e1ria\/2,3 da S\u00e9 \u2013 Lamego, integrados nas seguintes categorias: Categoria A (2.\u00ba Ciclo), Categoria B (3.\u00ba Ciclo) e Categoria C (Secund\u00e1rio).<\/li>\n<li>Est\u00e1 tamb\u00e9m aberta a participa\u00e7\u00e3o ao pessoal docente (com excep\u00e7\u00e3o de professores de Matem\u00e1tica) e ao pessoal n\u00e3o docente da Escola Secund\u00e1ria\/2,3 da S\u00e9 \u2013 Lamego, que concorrer\u00e1, em Categoria Especial, ao problema da Categoria B.<\/li>\n<li>Este desafio decorre de 24 de Mar\u00e7o a 13 de Abril de 2012.<\/li>\n<li>A resolu\u00e7\u00e3o do problema deve ser remetida por via electr\u00f3nica at\u00e9 \u00e0s 24 horas do dia 13 de Abril de 2012, nos termos a divulgar numa das etapas do desafio.<\/li>\n<li>S\u00e3o participantes vencedores todos aqueles que atinjam a \u00faltima etapa do desafio.<\/li>\n<li>Terminado o desafio, ser\u00e3o divulgados no <a href=\"https:\/\/blogs.ess-edu.pt\/sm2010\/\" target=\"_blank\" rel=\"noopener\">S\u00edtio com Matem\u00e1tica<\/a> os nomes dos participantes vencedores.<\/li>\n<li>Ser\u00e1 atribu\u00eddo um pr\u00e9mio por categoria, de acordo com a aprecia\u00e7\u00e3o do J\u00fari sobre a qualidade da resolu\u00e7\u00e3o apresentada.<\/li>\n<li>Todos os participantes no desafio aderem automaticamente a todas as cl\u00e1usulas deste regulamento.<\/li>\n<li>Os casos omissos do presente regulamento ser\u00e3o resolvidos pelo J\u00fari.<\/li>\n<\/ol>\n<p><a href=\"https:\/\/blogs.ess-edu.pt\/sm2010\/files\/2012\/03\/DSM-2012_cartaz1.pdf\">DSM-2012_cartaz1<\/a><\/p>\n<p><a href=\"https:\/\/blogs.ess-edu.pt\/sm2010\/files\/2012\/03\/DSM-2012_cartaz2.pdf\">DSM-2012_cartaz2<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Desafio da Semana da Matem\u00e1tica inclui a resolu\u00e7\u00e3o de um problema, cujo enunciado est\u00e1 numa p\u00e1gina, protegida por uma palavra-chave, do S\u00edtio com Matem\u00e1tica (https:\/\/blogs.ess-edu.pt\/sm2010\/). A palavra-chave de acesso ao enunciado \u00e9 a solu\u00e7\u00e3o da seguinte quest\u00e3o: A Palavra-chave Qual \u00e9 o s\u00e9timo termo da sequ\u00eancia 1, 2, 6, 24, 120, 720, _______ ? [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[174,40],"tags":[],"class_list":{"0":"post-328","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-desafios","7":"category-divulgacao","8":"czr-hentry"},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paunYK-5i","jetpack-related-posts":[{"id":134,"url":"https:\/\/blogs.ess-edu.pt\/sm2010\/2010\/03\/14\/desafio-da-semana-da-matematica\/","url_meta":{"origin":328,"position":0},"title":"Desafio da Semana da Matem\u00e1tica","author":"Ant\u00f3nio Amaral","date":"14 de Mar\u00e7o de 2010","format":false,"excerpt":"O Desafio da Semana da Matem\u00e1tica inclui a resolu\u00e7\u00e3o de um problema, cujo enunciado est\u00e1 numa p\u00e1gina, protegida por uma palavra-chave, do S\u00edtio com Matem\u00e1tica (https:\/\/blogs.ess-edu.pt\/sm2010\/). A palavra-chave de acesso ao enunciado \u00e9 a solu\u00e7\u00e3o do seguinte problema: A Palavra-chave Qual \u00e9 o sexto termo da sequ\u00eancia 1, 2, 6,\u2026","rel":"","context":"In &quot;Desafios&quot;","block_context":{"text":"Desafios","link":"https:\/\/blogs.ess-edu.pt\/sm2010\/category\/desafios\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/sm2010\/files\/2010\/03\/enigma13478-300x203.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":208,"url":"https:\/\/blogs.ess-edu.pt\/sm2010\/2011\/03\/10\/desafio-da-semana-da-matematica-2011\/","url_meta":{"origin":328,"position":1},"title":"Desafio da Semana da Matem\u00e1tica &#8211; 2011","author":"admin","date":"10 de Mar\u00e7o de 2011","format":false,"excerpt":"O Desafio da Semana da Matem\u00e1tica inclui a resolu\u00e7\u00e3o de um problema, cujo enunciado est\u00e1 numa p\u00e1gina, protegida por uma palavra-chave, do S\u00edtio com Matem\u00e1tica (https:\/\/blogs.ess-edu.pt\/sm2010\/). A palavra-chave de acesso ao enunciado \u00e9 a solu\u00e7\u00e3o do seguinte problema: A Palavra-chave Qual \u00e9 o s\u00e9timo termo da sequ\u00eancia 1, 2, 6,\u2026","rel":"","context":"In &quot;Divulga\u00e7\u00e3o&quot;","block_context":{"text":"Divulga\u00e7\u00e3o","link":"https:\/\/blogs.ess-edu.pt\/sm2010\/category\/divulgacao\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/sm2010\/files\/2010\/03\/enigma13478-300x203.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":158,"url":"https:\/\/blogs.ess-edu.pt\/sm2010\/2010\/07\/02\/a-historia-da-matematica\/","url_meta":{"origin":328,"position":2},"title":"A Hist\u00f3ria da Matem\u00e1tica","author":"Ant\u00f3nio Amaral","date":"2 de Julho de 2010","format":false,"excerpt":"The story of maths, document\u00e1rio produzido pela\u00a0BBC, conta a hist\u00f3ria da matem\u00e1tica e mostra a sua import\u00e2ncia para a nossa vida. Apresentado por Marcus du Sautoy, pesquisador e professor da Universidade de Oxford, o document\u00e1rio \u00e9 dividido em 4 epis\u00f3dios e est\u00e1 dispon\u00edvel no YouTube com legendas em portugu\u00eas. Esta\u2026","rel":"","context":"In &quot;Divulga\u00e7\u00e3o&quot;","block_context":{"text":"Divulga\u00e7\u00e3o","link":"https:\/\/blogs.ess-edu.pt\/sm2010\/category\/divulgacao\/"},"img":{"alt_text":"A Hist\u00f3ria da Matem\u00e1tica","src":"https:\/\/i0.wp.com\/www.acasinhadamatematica.pt\/wp\/wp-content\/uploads\/2010\/07\/TheStoryOfMaths.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":118,"url":"https:\/\/blogs.ess-edu.pt\/sm2010\/2010\/03\/09\/donald-no-pais-da-matematica\/","url_meta":{"origin":328,"position":3},"title":"Donald no Pa\u00eds da Matem\u00e1gica","author":"Ant\u00f3nio Amaral","date":"9 de Mar\u00e7o de 2010","format":false,"excerpt":"Donald no Pa\u00eds da Matem\u00e1gica (\"Donald in Mathmagic Land\") \u00e9 uma curta-metragem de 27 minutos em que a estrela \u00e9 o Pato Donald. O filme foi lan\u00e7ado nos EUA em 26 de junho de 1959 e foi dirigido por Hamilton Luske. O filme foi disponibilizado para v\u00e1rias escolas, e tornou-se\u2026","rel":"","context":"In &quot;Divulga\u00e7\u00e3o&quot;","block_context":{"text":"Divulga\u00e7\u00e3o","link":"https:\/\/blogs.ess-edu.pt\/sm2010\/category\/divulgacao\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":106,"url":"https:\/\/blogs.ess-edu.pt\/sm2010\/2010\/03\/08\/matematica-na-objectiva-concurso-de-fotografia\/","url_meta":{"origin":328,"position":4},"title":"Matem\u00e1tica na Objectiva &#8211; Concurso de Fotografia","author":"Ant\u00f3nio Amaral","date":"8 de Mar\u00e7o de 2010","format":false,"excerpt":"\u00a0 REGULAMENTO DO CONCURSO DE FOTOGRAFIA 1. Condi\u00e7\u00f5es de Participa\u00e7\u00e3o 1.1. A participa\u00e7\u00e3o est\u00e1 aberta aos alunos do 3.\u00ba Ciclo e Ensino Secund\u00e1rio da Escola B\u00e1sica e Secund\u00e1ria da S\u00e9 \u2013 Lamego, excepto membros do J\u00fari. 1.2. As fotografias dever\u00e3o ser in\u00e9ditas e satisfazer os requisitos do ponto 4 deste\u2026","rel":"","context":"In &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/blogs.ess-edu.pt\/sm2010\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/sm2010\/files\/2010\/03\/cartaz-matematica-na-objectiva.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/sm2010\/files\/2010\/03\/cartaz-matematica-na-objectiva.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/blogs.ess-edu.pt\/sm2010\/files\/2010\/03\/cartaz-matematica-na-objectiva.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":125,"url":"https:\/\/blogs.ess-edu.pt\/sm2010\/2010\/03\/12\/robotmania-2010\/","url_meta":{"origin":328,"position":5},"title":"ROBOTMANIA &#8216;2010","author":"Ant\u00f3nio Amaral","date":"12 de Mar\u00e7o de 2010","format":false,"excerpt":"No pr\u00f3ximo dia 26 de Mar\u00e7o, sexta-feira, integrado na Semana da Matem\u00e1tica, vai ter lugar, na Escola Superior de Tecnologia e Gest\u00e3o de Lamego, uma sess\u00e3o de rob\u00f3tica destinada aos alunos do Curso Profissional de T\u00e9cnico de Instala\u00e7\u00f5es El\u00e9ctricas da nossa Escola.","rel":"","context":"In &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/blogs.ess-edu.pt\/sm2010\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/blogs.ess-edu.pt\/sm2010\/files\/2010\/03\/rotmania2010-211x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/blogs.ess-edu.pt\/sm2010\/wp-json\/wp\/v2\/posts\/328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.ess-edu.pt\/sm2010\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.ess-edu.pt\/sm2010\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/sm2010\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/sm2010\/wp-json\/wp\/v2\/comments?post=328"}],"version-history":[{"count":0,"href":"https:\/\/blogs.ess-edu.pt\/sm2010\/wp-json\/wp\/v2\/posts\/328\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.ess-edu.pt\/sm2010\/wp-json\/wp\/v2\/media?parent=328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/sm2010\/wp-json\/wp\/v2\/categories?post=328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.ess-edu.pt\/sm2010\/wp-json\/wp\/v2\/tags?post=328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}